{"id":18258,"date":"2024-03-19T08:54:00","date_gmt":"2024-03-19T11:54:00","guid":{"rendered":"https:\/\/vetanco.com\/br\/?p=18258"},"modified":"2024-09-26T09:07:20","modified_gmt":"2024-09-26T12:07:20","slug":"vetanco-eleita-como-melhor-fornecedor-pela-brf","status":"publish","type":"post","link":"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/","title":{"rendered":"Vetanco eleita como Melhor Fornecedor pela BRF"},"content":{"rendered":"\n<p>A <a href=\"https:\/\/www.brf-global.com\/\" target=\"_blank\" rel=\"noopener\">BRF<\/a> elegeu a Vetanco como Melhor Fornecedor na categoria Feed \u2013 Modalidade Ouro do Programa Fornecedores de Excel\u00eancia. A cerim\u00f4nia de releva\u00e7\u00e3o aconteceu no dia 15 de mar\u00e7o, em Curitiba\/PR<\/p>\n<p>Durante o evento, Igor Campagnoni, Gerente de Contas Chave; Mareleusa Dumke Poletto, Gerente Administrativa\/Financeira; e Rosilei Riffel, Assistente Administrativa, representaram a Vetanco.<\/p>\n<p>\u201cEsse pr\u00eamio \u00e9 muito importante para n\u00f3s, pois reconhece que nosso projeto de atendimento com excel\u00eancia aos clientes est\u00e1 funcionando de forma diferenciada. Conseguimos entregar uma grande efici\u00eancia no pr\u00e9, durante e p\u00f3s-venda, tanto na parte administrativa e operacional quanto na t\u00e9cnica\u201d, avalia Campagnoni.<\/p>\n<h1>Parceria estabelecida<\/h1>\n<p>O Programa reconhece os fornecedores que se destacam no processo de compras da companhia, contribuindo assim para o sucesso das opera\u00e7\u00f5es. Al\u00e9m disso, incentiva a excel\u00eancia no atendimento, na qualidade dos produtos e servi\u00e7os oferecidos e na parceria estabelecida entre a BRF e o fornecedor.<\/p>\n<p>No total, mais de 400 fornecedores participaram do Programa Fornecedores de Excel\u00eancia da BRF. Eles foram avaliados durante seis meses, com base em mais de 250 mil pedidos de compras efetuados. Os indicadores do per\u00edodo de julho a dezembro de 2023 foram considerados na avalia\u00e7\u00e3o.<\/p>\n<p>\u201cFoi um momento muito especial, e o pr\u00eamio veio como resultado de um trabalho que exige muita aten\u00e7\u00e3o e envolvimento. Foi uma conquista muito merecida\u201d, comenta Rosilei. Ela tamb\u00e9m destacou o trabalho em equipe e mencionou as colaboradoras Marissandra Catureba Cruz e Ana Carolina Cella Maciel.<\/p>\n<p>Assim, a Vetanco reconhece a import\u00e2ncia de cada colaborador no processo e celebra essa conquista como de cada indiv\u00edduo que integra a corpora\u00e7\u00e3o.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":18272,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,45],"tags":[545,546],"class_list":["post-18258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-noticias","tag-melhor-fornecedor","tag-programa-de-excelencia-brf"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vetanco eleita como Melhor Fornecedor pela BRF - Vetanco Brasil<\/title>\n<meta name=\"description\" content=\"Fomos eleitos como Melhor Fornecedor na categoria Feed \u2013 Modalidade Ouro do Programa Fornecedores de Excel\u00eancia da BRF.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vetanco eleita como Melhor Fornecedor pela BRF - Vetanco Brasil\" \/>\n<meta property=\"og:description\" content=\"Fomos eleitos como Melhor Fornecedor na categoria Feed \u2013 Modalidade Ouro do Programa Fornecedores de Excel\u00eancia da BRF.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/\" \/>\n<meta property=\"og:site_name\" content=\"Vetanco Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-19T11:54:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T12:07:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vetanco.com\/br\/wp-content\/uploads\/2024\/09\/melhor-fornecedor-excelencia-brf-vetanco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Simone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Simone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/vetanco-eleita-como-melhor-fornecedor-pela-brf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/vetanco-eleita-como-melhor-fornecedor-pela-brf\\\/\"},\"author\":{\"name\":\"Simone\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/#\\\/schema\\\/person\\\/2f1ec2742b3d4f850572c66972a797de\"},\"headline\":\"Vetanco eleita como Melhor Fornecedor pela BRF\",\"datePublished\":\"2024-03-19T11:54:00+00:00\",\"dateModified\":\"2024-09-26T12:07:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/vetanco-eleita-como-melhor-fornecedor-pela-brf\\\/\"},\"wordCount\":284,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/vetanco-eleita-como-melhor-fornecedor-pela-brf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vetanco.com\\\/br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/melhor-fornecedor-excelencia-brf-vetanco.jpg\",\"keywords\":[\"Melhor Fornecedor\",\"Programa de Excel\u00eancia BRF\"],\"articleSection\":[\"Eventos\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vetanco.com\\\/br\\\/vetanco-eleita-como-melhor-fornecedor-pela-brf\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/vetanco-eleita-como-melhor-fornecedor-pela-brf\\\/\",\"url\":\"https:\\\/\\\/vetanco.com\\\/br\\\/vetanco-eleita-como-melhor-fornecedor-pela-brf\\\/\",\"name\":\"Vetanco eleita como Melhor Fornecedor pela BRF - Vetanco Brasil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/vetanco-eleita-como-melhor-fornecedor-pela-brf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/vetanco-eleita-como-melhor-fornecedor-pela-brf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vetanco.com\\\/br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/melhor-fornecedor-excelencia-brf-vetanco.jpg\",\"datePublished\":\"2024-03-19T11:54:00+00:00\",\"dateModified\":\"2024-09-26T12:07:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/#\\\/schema\\\/person\\\/2f1ec2742b3d4f850572c66972a797de\"},\"description\":\"Fomos eleitos como Melhor Fornecedor na categoria Feed \u2013 Modalidade Ouro do Programa Fornecedores de Excel\u00eancia da BRF.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/vetanco-eleita-como-melhor-fornecedor-pela-brf\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vetanco.com\\\/br\\\/vetanco-eleita-como-melhor-fornecedor-pela-brf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/vetanco-eleita-como-melhor-fornecedor-pela-brf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vetanco.com\\\/br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/melhor-fornecedor-excelencia-brf-vetanco.jpg\",\"contentUrl\":\"https:\\\/\\\/vetanco.com\\\/br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/melhor-fornecedor-excelencia-brf-vetanco.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/vetanco-eleita-como-melhor-fornecedor-pela-brf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/vetanco.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vetanco eleita como Melhor Fornecedor pela BRF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/vetanco.com\\\/br\\\/\",\"name\":\"Vetanco Brasil\",\"description\":\"Produtos Seguros para Alimentos Seguros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vetanco.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/#\\\/schema\\\/person\\\/2f1ec2742b3d4f850572c66972a797de\",\"name\":\"Simone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/simone-100x100.jpg\",\"url\":\"https:\\\/\\\/vetanco.com\\\/br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/simone-100x100.jpg\",\"contentUrl\":\"https:\\\/\\\/vetanco.com\\\/br\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/simone-100x100.jpg\",\"caption\":\"Simone\"},\"url\":\"https:\\\/\\\/vetanco.com\\\/br\\\/author\\\/sijantsch\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vetanco eleita como Melhor Fornecedor pela BRF - Vetanco Brasil","description":"Fomos eleitos como Melhor Fornecedor na categoria Feed \u2013 Modalidade Ouro do Programa Fornecedores de Excel\u00eancia da BRF.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/","og_locale":"pt_BR","og_type":"article","og_title":"Vetanco eleita como Melhor Fornecedor pela BRF - Vetanco Brasil","og_description":"Fomos eleitos como Melhor Fornecedor na categoria Feed \u2013 Modalidade Ouro do Programa Fornecedores de Excel\u00eancia da BRF.","og_url":"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/","og_site_name":"Vetanco Brasil","article_published_time":"2024-03-19T11:54:00+00:00","article_modified_time":"2024-09-26T12:07:20+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/vetanco.com\/br\/wp-content\/uploads\/2024\/09\/melhor-fornecedor-excelencia-brf-vetanco.jpg","type":"image\/jpeg"}],"author":"Simone","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Simone","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/#article","isPartOf":{"@id":"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/"},"author":{"name":"Simone","@id":"https:\/\/vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de"},"headline":"Vetanco eleita como Melhor Fornecedor pela BRF","datePublished":"2024-03-19T11:54:00+00:00","dateModified":"2024-09-26T12:07:20+00:00","mainEntityOfPage":{"@id":"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/"},"wordCount":284,"commentCount":0,"image":{"@id":"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/#primaryimage"},"thumbnailUrl":"https:\/\/vetanco.com\/br\/wp-content\/uploads\/2024\/09\/melhor-fornecedor-excelencia-brf-vetanco.jpg","keywords":["Melhor Fornecedor","Programa de Excel\u00eancia BRF"],"articleSection":["Eventos","Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/","url":"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/","name":"Vetanco eleita como Melhor Fornecedor pela BRF - Vetanco Brasil","isPartOf":{"@id":"https:\/\/vetanco.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/#primaryimage"},"image":{"@id":"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/#primaryimage"},"thumbnailUrl":"https:\/\/vetanco.com\/br\/wp-content\/uploads\/2024\/09\/melhor-fornecedor-excelencia-brf-vetanco.jpg","datePublished":"2024-03-19T11:54:00+00:00","dateModified":"2024-09-26T12:07:20+00:00","author":{"@id":"https:\/\/vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de"},"description":"Fomos eleitos como Melhor Fornecedor na categoria Feed \u2013 Modalidade Ouro do Programa Fornecedores de Excel\u00eancia da BRF.","breadcrumb":{"@id":"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/#primaryimage","url":"https:\/\/vetanco.com\/br\/wp-content\/uploads\/2024\/09\/melhor-fornecedor-excelencia-brf-vetanco.jpg","contentUrl":"https:\/\/vetanco.com\/br\/wp-content\/uploads\/2024\/09\/melhor-fornecedor-excelencia-brf-vetanco.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/vetanco.com\/br\/vetanco-eleita-como-melhor-fornecedor-pela-brf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/vetanco.com\/br\/"},{"@type":"ListItem","position":2,"name":"Vetanco eleita como Melhor Fornecedor pela BRF"}]},{"@type":"WebSite","@id":"https:\/\/vetanco.com\/br\/#website","url":"https:\/\/vetanco.com\/br\/","name":"Vetanco Brasil","description":"Produtos Seguros para Alimentos Seguros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vetanco.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/vetanco.com\/br\/#\/schema\/person\/2f1ec2742b3d4f850572c66972a797de","name":"Simone","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg","url":"https:\/\/vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg","contentUrl":"https:\/\/vetanco.com\/br\/wp-content\/uploads\/2024\/09\/simone-100x100.jpg","caption":"Simone"},"url":"https:\/\/vetanco.com\/br\/author\/sijantsch\/"}]}},"_links":{"self":[{"href":"https:\/\/vetanco.com\/br\/wp-json\/wp\/v2\/posts\/18258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vetanco.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vetanco.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vetanco.com\/br\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/vetanco.com\/br\/wp-json\/wp\/v2\/comments?post=18258"}],"version-history":[{"count":14,"href":"https:\/\/vetanco.com\/br\/wp-json\/wp\/v2\/posts\/18258\/revisions"}],"predecessor-version":[{"id":18273,"href":"https:\/\/vetanco.com\/br\/wp-json\/wp\/v2\/posts\/18258\/revisions\/18273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vetanco.com\/br\/wp-json\/wp\/v2\/media\/18272"}],"wp:attachment":[{"href":"https:\/\/vetanco.com\/br\/wp-json\/wp\/v2\/media?parent=18258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vetanco.com\/br\/wp-json\/wp\/v2\/categories?post=18258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vetanco.com\/br\/wp-json\/wp\/v2\/tags?post=18258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}