{"id":7343,"date":"2020-10-20T10:45:00","date_gmt":"2020-10-20T13:45:00","guid":{"rendered":"https:\/\/vetanco.com\/es\/?p=7343"},"modified":"2026-03-10T11:11:14","modified_gmt":"2026-03-10T14:11:14","slug":"nuevo-logro-la-lucha-la-covid-19","status":"publish","type":"post","link":"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/","title":{"rendered":"Un nuevo logro en la lucha contra la COVID-19"},"content":{"rendered":"\n\n\n<p class=\"wp-block-paragraph\"><em>Un equipo multidisciplinario en el que participa la empresa Bioinnovo SA desarroll\u00f3 anticuerpos aviares IgY que neutralizan el virus que causa la COVID-19.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"681\" src=\"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/201020091052-1024x681-1.jpg\" alt=\"\" class=\"wp-image-7344\" srcset=\"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/201020091052-1024x681-1.jpg 1024w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/201020091052-1024x681-1-300x200.jpg 300w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/201020091052-1024x681-1-768x511.jpg 768w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/201020091052-1024x681-1-510x339.jpg 510w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Foto INTA<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es en el marco del proyecto denominado \u201cDesarrollo y producci\u00f3n de reactivos cr\u00edticos para diagn\u00f3stico y tratamiento de COVID-19: Nanoanticuerpos<em>, anticuerpos policlonales IgY y prote\u00ednas recombinantes\u201d&nbsp;<\/em>investigadores del&nbsp;<a href=\"https:\/\/www.argentina.gob.ar\/inta\" target=\"_blank\" rel=\"noreferrer noopener\">INTA<\/a>,&nbsp;<a href=\"https:\/\/www.conicet.gov.ar\/\" target=\"_blank\" rel=\"noreferrer noopener\">CONICET<\/a>, el Instituto Nacional de Enfermedades Infecciosas (<a href=\"http:\/\/sgc.anlis.gob.ar\/\" target=\"_blank\" rel=\"noreferrer noopener\">INEI<\/a>) de la ANLIS-Malbr\u00e1n, el consorcio anti Covid 19 liderado por la Facultad de Ciencias Exactas y Naturales de la UBA, y la empresa&nbsp;<a href=\"http:\/\/bioinnovo.com.ar\/\">Bioinnovo SA<\/a>&nbsp;-EBT formada por INTA y&nbsp;<a href=\"https:\/\/vetanco.com\/\">Vetanco SA<\/a>-.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los VHH \u2013nanoanticuerpos monoclonales recombinantes- y los IgY \u2013anticuerpos policlonales- representan dos estrategias como tratamiento preventivo y herramienta terap\u00e9utica para pacientes afectados de COVID-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas mol\u00e9culas desarrolladas como parte del proyecto obtenido por el&nbsp;<a href=\"https:\/\/www.argentina.gob.ar\/inta\" target=\"_blank\" rel=\"noreferrer noopener\">INTA<\/a>&nbsp;en la convocatoria COVID-19 del&nbsp;<a href=\"https:\/\/www.argentina.gob.ar\/ciencia\" target=\"_blank\" rel=\"noreferrer noopener\">MINCYT<\/a>, tienen la potencialidad de convertirse en productos. Su aplicaci\u00f3n ser\u00e1 como shock inmunoterape\u00fatico para el tratamiento de la enfermedad de COVID-19, complementario a otros m\u00e9todos disponibles y vacunas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los ensayos de la actividad neutralizante de las mol\u00e9culas desarrolladas por el equipo de la Dra. Viviana Parre\u00f1o, coordinadora cient\u00edfica de INCUINTA del INTA, fueron recientemente comprobados en la Argentina por la Dra. Itat\u00ed Ib\u00e1\u00f1ez \u2013CONICET- con pseudo part\u00edculas virales y, paralelamente, en los Estados Unidos por el Dr. Jonathan&nbsp;Auguste, del Instituto Polit\u00e9cnico de Virginia, que analiz\u00f3 las mol\u00e9culas en un ensayo con el virus salvaje. Adem\u00e1s de las pruebas realizadas en el Instituto Malbr\u00e1n que as\u00ed tambi\u00e9n lo demuestran.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El INTA cuenta hoy con dos estrategias de inmunidad pasiva contra el SARS-CoV-2: una enfocada en la fabricaci\u00f3n de un poli monoclonal a partir de los VHH de llama, lo que representa distintos monoclonales en un mismo c\u00f3ctel; y otra en la que participa<strong>&nbsp;<a href=\"https:\/\/www.bioinnovo.com.ar\/intro\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bioinnovo<\/a><\/strong>, con los IgY, que son anticuerpos policlonales m\u00e1s econ\u00f3micos, f\u00e1ciles de escalar y que cumplen con las normas de bienestar animal. Ambas plataformas presentan la posibilidad de tener un alcance masivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos resultados obtenidos posicionan a la Argentina entre los pa\u00edses que han desarrollado sus \u201cnanobodies\u201d como Estados Unidos, China, Suecia y B\u00e9lgica, entre otras naciones de la Uni\u00f3n Europea, siendo el primer pa\u00eds del hemisferio sur en dar cuenta de este logro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalizadas las pruebas de seguridad en animales en las pr\u00f3ximas semanas, se podr\u00e1 comenzar con la fase de escalado y pruebas cl\u00ednicas, con la aprobaci\u00f3n de la autoridad regulatoria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre el proyecto<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este desarrollo cont\u00f3 con el financiamiento de la Agencia de Promoci\u00f3n de la Investigaci\u00f3n, el Desarrollo y la Innovaci\u00f3n, INCUINTA, la cartera de proyectos INTA, y el Proyecto para la promoci\u00f3n del Nagoya en la Argentina (GEF\/PNUD).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, es apoyado por empresas farmac\u00e9uticas argentinas y de investigadores del Centro de Investigaci\u00f3n de Vacunas (VRC) del NIH y del Hospital Monte Sina\u00ed -Nueva York, ambos de los Estados Unidos, y Consejo Nacional de Investigaci\u00f3n de Canad\u00e1&nbsp; (NRCC).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Antecedente<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La obtenci\u00f3n de nanoanticuerpos monoclonales y de anticuerpos IgY es producto de investigaciones que desde el a\u00f1o 2005 desarrolla la plataforma INCUINTA, que trabaja en el desarrollo de plataformas para la producci\u00f3n de anticuerpos bajo el concepto de \u201cUna Salud\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s informaci\u00f3n en:&nbsp;<a href=\"https:\/\/bit.ly\/35fJB27\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/bit.ly\/35fJB27<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un equipo multidisciplinario en el que participa la empresa Bioinnovo SA desarroll\u00f3 anticuerpos aviares IgY que neutralizan el virus que causa la COVID-19. Foto INTA Es en el marco del proyecto denominado \u201cDesarrollo y producci\u00f3n de reactivos cr\u00edticos para diagn\u00f3stico y tratamiento de COVID-19: Nanoanticuerpos, anticuerpos policlonales IgY y prote\u00ednas recombinantes\u201d&nbsp;investigadores del&nbsp;INTA,&nbsp;CONICET, el Instituto Nacional [&#8230;]\n","protected":false},"author":6,"featured_media":7344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[117,107,118,37,40,58],"class_list":["post-7343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades","tag-bioinnovo-sa","tag-conicet","tag-covid-19","tag-incuinta","tag-inta","tag-vetanco-sa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un nuevo logro en la lucha contra la COVID-19 - Vetanco Argentina<\/title>\n<meta name=\"description\" content=\"Un equipo multidisciplinario en el que participa la empresa Bioinnovo SA desarroll\u00f3 anticuerpos aviares IgY que neutralizan el virus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un nuevo logro en la lucha contra la COVID-19 - Vetanco Argentina\" \/>\n<meta property=\"og:description\" content=\"Un equipo multidisciplinario en el que participa la empresa Bioinnovo SA desarroll\u00f3 anticuerpos aviares IgY que neutralizan el virus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Vetanco Argentina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vetancoargentina\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-20T13:45:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T14:11:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/201020091052-1024x681-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"681\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"evangelinamenghini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"evangelinamenghini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/nuevo-logro-la-lucha-la-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/nuevo-logro-la-lucha-la-covid-19\\\/\"},\"author\":{\"name\":\"evangelinamenghini\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#\\\/schema\\\/person\\\/4a333212148c551e5d1f9d99a5cbb716\"},\"headline\":\"Un nuevo logro en la lucha contra la COVID-19\",\"datePublished\":\"2020-10-20T13:45:00+00:00\",\"dateModified\":\"2026-03-10T14:11:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/nuevo-logro-la-lucha-la-covid-19\\\/\"},\"wordCount\":583,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/nuevo-logro-la-lucha-la-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vetanco.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/201020091052-1024x681-1.jpg\",\"keywords\":[\"Bioinnovo SA\",\"CONICET\",\"COVID-19\",\"INCUINTA\",\"INTA\",\"Vetanco SA\"],\"articleSection\":[\"Novedades\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vetanco.com\\\/es\\\/nuevo-logro-la-lucha-la-covid-19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/nuevo-logro-la-lucha-la-covid-19\\\/\",\"url\":\"https:\\\/\\\/vetanco.com\\\/es\\\/nuevo-logro-la-lucha-la-covid-19\\\/\",\"name\":\"Un nuevo logro en la lucha contra la COVID-19 - Vetanco Argentina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/nuevo-logro-la-lucha-la-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/nuevo-logro-la-lucha-la-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vetanco.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/201020091052-1024x681-1.jpg\",\"datePublished\":\"2020-10-20T13:45:00+00:00\",\"dateModified\":\"2026-03-10T14:11:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#\\\/schema\\\/person\\\/4a333212148c551e5d1f9d99a5cbb716\"},\"description\":\"Un equipo multidisciplinario en el que participa la empresa Bioinnovo SA desarroll\u00f3 anticuerpos aviares IgY que neutralizan el virus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/nuevo-logro-la-lucha-la-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vetanco.com\\\/es\\\/nuevo-logro-la-lucha-la-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/nuevo-logro-la-lucha-la-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vetanco.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/201020091052-1024x681-1.jpg\",\"contentUrl\":\"https:\\\/\\\/vetanco.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/201020091052-1024x681-1.jpg\",\"width\":1024,\"height\":681},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/nuevo-logro-la-lucha-la-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/vetanco.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un nuevo logro en la lucha contra la COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vetanco.com\\\/es\\\/\",\"name\":\"Vetanco Argentina\",\"description\":\"Productos Seguros para Alimentos Seguros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vetanco.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#\\\/schema\\\/person\\\/4a333212148c551e5d1f9d99a5cbb716\",\"name\":\"evangelinamenghini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08f726e9876e489e5034751b2c3ddf9c39dcd219012a94cd42e52ea935b5eeef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08f726e9876e489e5034751b2c3ddf9c39dcd219012a94cd42e52ea935b5eeef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08f726e9876e489e5034751b2c3ddf9c39dcd219012a94cd42e52ea935b5eeef?s=96&d=mm&r=g\",\"caption\":\"evangelinamenghini\"},\"url\":\"https:\\\/\\\/vetanco.com\\\/es\\\/author\\\/evangelinamenghini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un nuevo logro en la lucha contra la COVID-19 - Vetanco Argentina","description":"Un equipo multidisciplinario en el que participa la empresa Bioinnovo SA desarroll\u00f3 anticuerpos aviares IgY que neutralizan el virus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/","og_locale":"es_ES","og_type":"article","og_title":"Un nuevo logro en la lucha contra la COVID-19 - Vetanco Argentina","og_description":"Un equipo multidisciplinario en el que participa la empresa Bioinnovo SA desarroll\u00f3 anticuerpos aviares IgY que neutralizan el virus.","og_url":"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/","og_site_name":"Vetanco Argentina","article_publisher":"https:\/\/www.facebook.com\/vetancoargentina","article_published_time":"2020-10-20T13:45:00+00:00","article_modified_time":"2026-03-10T14:11:14+00:00","og_image":[{"width":1024,"height":681,"url":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/201020091052-1024x681-1.jpg","type":"image\/jpeg"}],"author":"evangelinamenghini","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"evangelinamenghini","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/#article","isPartOf":{"@id":"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/"},"author":{"name":"evangelinamenghini","@id":"https:\/\/vetanco.com\/es\/#\/schema\/person\/4a333212148c551e5d1f9d99a5cbb716"},"headline":"Un nuevo logro en la lucha contra la COVID-19","datePublished":"2020-10-20T13:45:00+00:00","dateModified":"2026-03-10T14:11:14+00:00","mainEntityOfPage":{"@id":"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/"},"wordCount":583,"commentCount":0,"image":{"@id":"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/201020091052-1024x681-1.jpg","keywords":["Bioinnovo SA","CONICET","COVID-19","INCUINTA","INTA","Vetanco SA"],"articleSection":["Novedades"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/","url":"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/","name":"Un nuevo logro en la lucha contra la COVID-19 - Vetanco Argentina","isPartOf":{"@id":"https:\/\/vetanco.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/201020091052-1024x681-1.jpg","datePublished":"2020-10-20T13:45:00+00:00","dateModified":"2026-03-10T14:11:14+00:00","author":{"@id":"https:\/\/vetanco.com\/es\/#\/schema\/person\/4a333212148c551e5d1f9d99a5cbb716"},"description":"Un equipo multidisciplinario en el que participa la empresa Bioinnovo SA desarroll\u00f3 anticuerpos aviares IgY que neutralizan el virus.","breadcrumb":{"@id":"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/#primaryimage","url":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/201020091052-1024x681-1.jpg","contentUrl":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/201020091052-1024x681-1.jpg","width":1024,"height":681},{"@type":"BreadcrumbList","@id":"https:\/\/vetanco.com\/es\/nuevo-logro-la-lucha-la-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/vetanco.com\/es\/"},{"@type":"ListItem","position":2,"name":"Un nuevo logro en la lucha contra la COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/vetanco.com\/es\/#website","url":"https:\/\/vetanco.com\/es\/","name":"Vetanco Argentina","description":"Productos Seguros para Alimentos Seguros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vetanco.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/vetanco.com\/es\/#\/schema\/person\/4a333212148c551e5d1f9d99a5cbb716","name":"evangelinamenghini","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/08f726e9876e489e5034751b2c3ddf9c39dcd219012a94cd42e52ea935b5eeef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/08f726e9876e489e5034751b2c3ddf9c39dcd219012a94cd42e52ea935b5eeef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08f726e9876e489e5034751b2c3ddf9c39dcd219012a94cd42e52ea935b5eeef?s=96&d=mm&r=g","caption":"evangelinamenghini"},"url":"https:\/\/vetanco.com\/es\/author\/evangelinamenghini\/"}]}},"_links":{"self":[{"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/posts\/7343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/comments?post=7343"}],"version-history":[{"count":3,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/posts\/7343\/revisions"}],"predecessor-version":[{"id":15559,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/posts\/7343\/revisions\/15559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/media\/7344"}],"wp:attachment":[{"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/media?parent=7343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/categories?post=7343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/tags?post=7343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}