{"id":7526,"date":"2019-11-22T11:28:00","date_gmt":"2019-11-22T14:28:00","guid":{"rendered":"https:\/\/vetanco.com\/es\/?p=7526"},"modified":"2024-10-21T09:36:34","modified_gmt":"2024-10-21T12:36:34","slug":"jornada-actualizacion-avicola-salmonelosis","status":"publish","type":"post","link":"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/","title":{"rendered":"Jornada de Actualizaci\u00f3n Av\u00edcola sobre Salmonelosis"},"content":{"rendered":"\n\n\n<p>El pasado viernes 15 de noviembre en la Facultad de Ciencias Veterinarias de la UBA, se llev\u00f3 a cabo la&nbsp;<strong>Jornada de Actualizaci\u00f3n Av\u00edcola sobre Salmonelosis<\/strong><em>, una mirada global de la Problem\u00e1tica Actual en el Sistema Productivo y Sanitario Av\u00edcola<\/em>.&nbsp;El evento&nbsp;fue organizado conjuntamente por la Secretar\u00eda de Extensi\u00f3n de la FCV -UBA y por la C\u00e1tedra de Producci\u00f3n de Aves FCV UBA, y coordinado por Marcela V\u00e1zquez y Marcelo Leone. All\u00ed estuvieron presentes profesionales de Vetanco disertando para alumnos y profesionales de la industria.<\/p>\n\n\n\n<p>El evento comenz\u00f3 con unas palabras de&nbsp;bienvenida, a cargo de In\u00e9s Delfino, Subsecretaria de Extensi\u00f3n. Luego se llevaron a cabo las charlas t\u00e9cnicas: El Dr. Pablo A. Chacana, Investigador del INTA Castelar, se refiri\u00f3 a&nbsp;<em>Salmonella en la Producci\u00f3n av\u00edcola, un problema de Salud P\u00fablica y Veterinaria<\/em>; luego fue el turno del&nbsp;MV. Emanuel R. Gumina, Responsable del Laboratorio de Biotecnolog\u00eda de Vetanco, quien present\u00f3 los&nbsp;<em>M\u00e9todos diagn\u00f3sticos para el aislamiento e identificaci\u00f3n de Salmonella spp en Avicultura.&nbsp;<\/em>Finalmente tuvo la palabra el MV&nbsp;Gonzalo E. Almaraz, Representante de Vetas de la Divisi\u00f3n de Aves de Vetanco, con su charla sobre&nbsp;<em>Herramientas de Control y Prevenci\u00f3n de Salmonella spp en Avicultura Industrial.<\/em><\/p>\n\n\n\n<p>Agradecemos especialmente a Paula Carancci e In\u00e9s Delfino Flood, de la<strong>&nbsp;<\/strong>Secretar\u00eda Acad\u00e9mica, y a&nbsp;Marcela V\u00e1zquez, de la&nbsp;C\u00e1tedra de Producci\u00f3n Av\u00edcola, por habernos tenido en consideraci\u00f3n para compartir esta jornada de capacitaci\u00f3n que contribuyen al perfeccionamiento acad\u00e9mico de los profesionales de nuestro pa\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0038-1024x1024.jpg\" alt=\"\" class=\"wp-image-7527\" srcset=\"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0038-1024x1024.jpg 1024w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0038-300x300.jpg 300w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0038-150x150.jpg 150w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0038-768x768.jpg 768w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0038-510x510.jpg 510w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0038-100x100.jpg 100w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0038.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0036-1024x1024.jpg\" alt=\"\" class=\"wp-image-7528\" srcset=\"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0036-1024x1024.jpg 1024w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0036-300x300.jpg 300w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0036-150x150.jpg 150w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0036-768x768.jpg 768w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0036-510x510.jpg 510w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0036-100x100.jpg 100w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0036.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0033-1024x1024.jpg\" alt=\"\" class=\"wp-image-7529\" srcset=\"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0033-1024x1024.jpg 1024w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0033-300x300.jpg 300w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0033-150x150.jpg 150w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0033-768x768.jpg 768w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0033-510x510.jpg 510w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0033-100x100.jpg 100w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0033.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0031-1024x1024.jpg\" alt=\"\" class=\"wp-image-7530\" srcset=\"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0031-1024x1024.jpg 1024w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0031-300x300.jpg 300w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0031-150x150.jpg 150w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0031-768x768.jpg 768w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0031-510x510.jpg 510w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0031-100x100.jpg 100w, https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0031.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El pasado viernes 15 de noviembre en la Facultad de Ciencias Veterinarias de la UBA, se llev\u00f3 a cabo la&nbsp;Jornada de Actualizaci\u00f3n Av\u00edcola sobre Salmonelosis, una mirada global de la Problem\u00e1tica Actual en el Sistema Productivo y Sanitario Av\u00edcola.&nbsp;El evento&nbsp;fue organizado conjuntamente por la Secretar\u00eda de Extensi\u00f3n de la FCV -UBA y por la C\u00e1tedra [&#8230;]\n","protected":false},"author":6,"featured_media":7529,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,31],"tags":[195,40,194,196,41],"class_list":["post-7526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-charlas-tecnicas","category-novedades","tag-fcv-uba","tag-inta","tag-jornada-de-actualizacion-avicola","tag-salmonelosis","tag-vetanco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jornada de Actualizaci\u00f3n Av\u00edcola sobre Salmonelosis - Vetanco Argentina<\/title>\n<meta name=\"description\" content=\"El evento\u00a0fue organizado conjuntamente por la Secretar\u00eda de Extensi\u00f3n de la FCV -UBA y por la C\u00e1tedra de Producci\u00f3n de Aves FCV UBA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jornada de Actualizaci\u00f3n Av\u00edcola sobre Salmonelosis - Vetanco Argentina\" \/>\n<meta property=\"og:description\" content=\"El evento\u00a0fue organizado conjuntamente por la Secretar\u00eda de Extensi\u00f3n de la FCV -UBA y por la C\u00e1tedra de Producci\u00f3n de Aves FCV UBA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/\" \/>\n<meta property=\"og:site_name\" content=\"Vetanco Argentina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vetancoargentina\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-22T14:28:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-21T12:36:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0033.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"evangelinamenghini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"evangelinamenghini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jornada-actualizacion-avicola-salmonelosis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jornada-actualizacion-avicola-salmonelosis\\\/\"},\"author\":{\"name\":\"evangelinamenghini\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#\\\/schema\\\/person\\\/4a333212148c551e5d1f9d99a5cbb716\"},\"headline\":\"Jornada de Actualizaci\u00f3n Av\u00edcola sobre Salmonelosis\",\"datePublished\":\"2019-11-22T14:28:00+00:00\",\"dateModified\":\"2024-10-21T12:36:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jornada-actualizacion-avicola-salmonelosis\\\/\"},\"wordCount\":296,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jornada-actualizacion-avicola-salmonelosis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vetanco.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMG-20191122-WA0033.jpg\",\"keywords\":[\"FCV UBA\",\"INTA\",\"Jornada de Actualizaci\u00f3n Av\u00edcola\",\"Salmonelosis\",\"Vetanco\"],\"articleSection\":[\"Charlas T\u00e9cnicas\",\"Novedades\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vetanco.com\\\/es\\\/jornada-actualizacion-avicola-salmonelosis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jornada-actualizacion-avicola-salmonelosis\\\/\",\"url\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jornada-actualizacion-avicola-salmonelosis\\\/\",\"name\":\"Jornada de Actualizaci\u00f3n Av\u00edcola sobre Salmonelosis - Vetanco Argentina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jornada-actualizacion-avicola-salmonelosis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jornada-actualizacion-avicola-salmonelosis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vetanco.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMG-20191122-WA0033.jpg\",\"datePublished\":\"2019-11-22T14:28:00+00:00\",\"dateModified\":\"2024-10-21T12:36:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#\\\/schema\\\/person\\\/4a333212148c551e5d1f9d99a5cbb716\"},\"description\":\"El evento\u00a0fue organizado conjuntamente por la Secretar\u00eda de Extensi\u00f3n de la FCV -UBA y por la C\u00e1tedra de Producci\u00f3n de Aves FCV UBA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jornada-actualizacion-avicola-salmonelosis\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vetanco.com\\\/es\\\/jornada-actualizacion-avicola-salmonelosis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jornada-actualizacion-avicola-salmonelosis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vetanco.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMG-20191122-WA0033.jpg\",\"contentUrl\":\"https:\\\/\\\/vetanco.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMG-20191122-WA0033.jpg\",\"width\":1280,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jornada-actualizacion-avicola-salmonelosis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/vetanco.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jornada de Actualizaci\u00f3n Av\u00edcola sobre Salmonelosis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vetanco.com\\\/es\\\/\",\"name\":\"Vetanco Argentina\",\"description\":\"Productos Seguros para Alimentos Seguros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vetanco.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#\\\/schema\\\/person\\\/4a333212148c551e5d1f9d99a5cbb716\",\"name\":\"evangelinamenghini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08f726e9876e489e5034751b2c3ddf9c39dcd219012a94cd42e52ea935b5eeef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08f726e9876e489e5034751b2c3ddf9c39dcd219012a94cd42e52ea935b5eeef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08f726e9876e489e5034751b2c3ddf9c39dcd219012a94cd42e52ea935b5eeef?s=96&d=mm&r=g\",\"caption\":\"evangelinamenghini\"},\"url\":\"https:\\\/\\\/vetanco.com\\\/es\\\/author\\\/evangelinamenghini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jornada de Actualizaci\u00f3n Av\u00edcola sobre Salmonelosis - Vetanco Argentina","description":"El evento\u00a0fue organizado conjuntamente por la Secretar\u00eda de Extensi\u00f3n de la FCV -UBA y por la C\u00e1tedra de Producci\u00f3n de Aves FCV UBA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/","og_locale":"es_ES","og_type":"article","og_title":"Jornada de Actualizaci\u00f3n Av\u00edcola sobre Salmonelosis - Vetanco Argentina","og_description":"El evento\u00a0fue organizado conjuntamente por la Secretar\u00eda de Extensi\u00f3n de la FCV -UBA y por la C\u00e1tedra de Producci\u00f3n de Aves FCV UBA.","og_url":"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/","og_site_name":"Vetanco Argentina","article_publisher":"https:\/\/www.facebook.com\/vetancoargentina","article_published_time":"2019-11-22T14:28:00+00:00","article_modified_time":"2024-10-21T12:36:34+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0033.jpg","type":"image\/jpeg"}],"author":"evangelinamenghini","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"evangelinamenghini","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/#article","isPartOf":{"@id":"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/"},"author":{"name":"evangelinamenghini","@id":"https:\/\/vetanco.com\/es\/#\/schema\/person\/4a333212148c551e5d1f9d99a5cbb716"},"headline":"Jornada de Actualizaci\u00f3n Av\u00edcola sobre Salmonelosis","datePublished":"2019-11-22T14:28:00+00:00","dateModified":"2024-10-21T12:36:34+00:00","mainEntityOfPage":{"@id":"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/"},"wordCount":296,"commentCount":0,"image":{"@id":"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/#primaryimage"},"thumbnailUrl":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0033.jpg","keywords":["FCV UBA","INTA","Jornada de Actualizaci\u00f3n Av\u00edcola","Salmonelosis","Vetanco"],"articleSection":["Charlas T\u00e9cnicas","Novedades"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/","url":"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/","name":"Jornada de Actualizaci\u00f3n Av\u00edcola sobre Salmonelosis - Vetanco Argentina","isPartOf":{"@id":"https:\/\/vetanco.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/#primaryimage"},"image":{"@id":"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/#primaryimage"},"thumbnailUrl":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0033.jpg","datePublished":"2019-11-22T14:28:00+00:00","dateModified":"2024-10-21T12:36:34+00:00","author":{"@id":"https:\/\/vetanco.com\/es\/#\/schema\/person\/4a333212148c551e5d1f9d99a5cbb716"},"description":"El evento\u00a0fue organizado conjuntamente por la Secretar\u00eda de Extensi\u00f3n de la FCV -UBA y por la C\u00e1tedra de Producci\u00f3n de Aves FCV UBA.","breadcrumb":{"@id":"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/#primaryimage","url":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0033.jpg","contentUrl":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/IMG-20191122-WA0033.jpg","width":1280,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/vetanco.com\/es\/jornada-actualizacion-avicola-salmonelosis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/vetanco.com\/es\/"},{"@type":"ListItem","position":2,"name":"Jornada de Actualizaci\u00f3n Av\u00edcola sobre Salmonelosis"}]},{"@type":"WebSite","@id":"https:\/\/vetanco.com\/es\/#website","url":"https:\/\/vetanco.com\/es\/","name":"Vetanco Argentina","description":"Productos Seguros para Alimentos Seguros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vetanco.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/vetanco.com\/es\/#\/schema\/person\/4a333212148c551e5d1f9d99a5cbb716","name":"evangelinamenghini","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/08f726e9876e489e5034751b2c3ddf9c39dcd219012a94cd42e52ea935b5eeef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/08f726e9876e489e5034751b2c3ddf9c39dcd219012a94cd42e52ea935b5eeef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08f726e9876e489e5034751b2c3ddf9c39dcd219012a94cd42e52ea935b5eeef?s=96&d=mm&r=g","caption":"evangelinamenghini"},"url":"https:\/\/vetanco.com\/es\/author\/evangelinamenghini\/"}]}},"_links":{"self":[{"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/posts\/7526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/comments?post=7526"}],"version-history":[{"count":1,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/posts\/7526\/revisions"}],"predecessor-version":[{"id":7531,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/posts\/7526\/revisions\/7531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/media\/7529"}],"wp:attachment":[{"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/media?parent=7526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/categories?post=7526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/tags?post=7526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}