{"id":9021,"date":"2017-02-14T10:35:00","date_gmt":"2017-02-14T13:35:00","guid":{"rendered":"https:\/\/vetanco.com\/es\/?p=9021"},"modified":"2024-09-19T10:43:43","modified_gmt":"2024-09-19T13:43:43","slug":"jorge-winokur-entrevistado-engormix","status":"publish","type":"post","link":"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/","title":{"rendered":"Jorge Winokur, entrevistado por Engormix en IPPE 2017"},"content":{"rendered":"\n\n\n<p class=\"wp-block-paragraph\">Jorge Winokur, Presidente de Vetanco, en entrevista con Engormix, habl\u00f3 sobre la presencia de la empresa en IPPE 2017 y los desaf\u00edos a los que se enfrenta la industria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.engormix.com\/MA-porcicultura\/videos\/vetanco-presente-ippe-2017-jorge-winokur-presidente-t46048.htm\">Acceda a la entrevista aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jorge Winokur, Presidente de Vetanco, en entrevista con Engormix, habl\u00f3 sobre la presencia de la empresa en IPPE 2017 y los desaf\u00edos a los que se enfrenta la industria. Acceda a la entrevista aqu\u00ed<\/p>\n","protected":false},"author":8,"featured_media":9022,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,31],"tags":[502,501,41],"class_list":["post-9021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-novedades","tag-engormix","tag-jorge-winokur","tag-vetanco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jorge Winokur, entrevistado por Engormix en IPPE 2017 - Vetanco Argentina<\/title>\n<meta name=\"description\" content=\"El presidente del laboratorio habl\u00f3 sobre la presencia de la empresa en IPPE 2017 y los desaf\u00edos a los que se enfrenta la industria.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jorge Winokur, entrevistado por Engormix en IPPE 2017 - Vetanco Argentina\" \/>\n<meta property=\"og:description\" content=\"El presidente del laboratorio habl\u00f3 sobre la presencia de la empresa en IPPE 2017 y los desaf\u00edos a los que se enfrenta la industria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/\" \/>\n<meta property=\"og:site_name\" content=\"Vetanco Argentina\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vetancoargentina\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-14T13:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-19T13:43:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-19-103708.png\" \/>\n\t<meta property=\"og:image:width\" content=\"936\" \/>\n\t<meta property=\"og:image:height\" content=\"728\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"julian\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"julian\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jorge-winokur-entrevistado-engormix\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jorge-winokur-entrevistado-engormix\\\/\"},\"author\":{\"name\":\"julian\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#\\\/schema\\\/person\\\/46afb38cfab0fe11bf52a9ded679bfcd\"},\"headline\":\"Jorge Winokur, entrevistado por Engormix en IPPE 2017\",\"datePublished\":\"2017-02-14T13:35:00+00:00\",\"dateModified\":\"2024-09-19T13:43:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jorge-winokur-entrevistado-engormix\\\/\"},\"wordCount\":41,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jorge-winokur-entrevistado-engormix\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vetanco.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Captura-de-pantalla-2024-09-19-103708.png\",\"keywords\":[\"Engormix\",\"Jorge Winokur\",\"Vetanco\"],\"articleSection\":[\"Eventos\",\"Novedades\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/vetanco.com\\\/es\\\/jorge-winokur-entrevistado-engormix\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jorge-winokur-entrevistado-engormix\\\/\",\"url\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jorge-winokur-entrevistado-engormix\\\/\",\"name\":\"Jorge Winokur, entrevistado por Engormix en IPPE 2017 - Vetanco Argentina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jorge-winokur-entrevistado-engormix\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jorge-winokur-entrevistado-engormix\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vetanco.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Captura-de-pantalla-2024-09-19-103708.png\",\"datePublished\":\"2017-02-14T13:35:00+00:00\",\"dateModified\":\"2024-09-19T13:43:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#\\\/schema\\\/person\\\/46afb38cfab0fe11bf52a9ded679bfcd\"},\"description\":\"El presidente del laboratorio habl\u00f3 sobre la presencia de la empresa en IPPE 2017 y los desaf\u00edos a los que se enfrenta la industria.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jorge-winokur-entrevistado-engormix\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vetanco.com\\\/es\\\/jorge-winokur-entrevistado-engormix\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jorge-winokur-entrevistado-engormix\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vetanco.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Captura-de-pantalla-2024-09-19-103708.png\",\"contentUrl\":\"https:\\\/\\\/vetanco.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Captura-de-pantalla-2024-09-19-103708.png\",\"width\":936,\"height\":728},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/jorge-winokur-entrevistado-engormix\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/vetanco.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jorge Winokur, entrevistado por Engormix en IPPE 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/vetanco.com\\\/es\\\/\",\"name\":\"Vetanco Argentina\",\"description\":\"Productos Seguros para Alimentos Seguros\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vetanco.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vetanco.com\\\/es\\\/#\\\/schema\\\/person\\\/46afb38cfab0fe11bf52a9ded679bfcd\",\"name\":\"julian\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc79426ed0651bb3545f906602e15ffcf6e4bdb7b02b2394b18705841d207f29?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc79426ed0651bb3545f906602e15ffcf6e4bdb7b02b2394b18705841d207f29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc79426ed0651bb3545f906602e15ffcf6e4bdb7b02b2394b18705841d207f29?s=96&d=mm&r=g\",\"caption\":\"julian\"},\"url\":\"https:\\\/\\\/vetanco.com\\\/es\\\/author\\\/julian\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jorge Winokur, entrevistado por Engormix en IPPE 2017 - Vetanco Argentina","description":"El presidente del laboratorio habl\u00f3 sobre la presencia de la empresa en IPPE 2017 y los desaf\u00edos a los que se enfrenta la industria.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/","og_locale":"es_ES","og_type":"article","og_title":"Jorge Winokur, entrevistado por Engormix en IPPE 2017 - Vetanco Argentina","og_description":"El presidente del laboratorio habl\u00f3 sobre la presencia de la empresa en IPPE 2017 y los desaf\u00edos a los que se enfrenta la industria.","og_url":"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/","og_site_name":"Vetanco Argentina","article_publisher":"https:\/\/www.facebook.com\/vetancoargentina","article_published_time":"2017-02-14T13:35:00+00:00","article_modified_time":"2024-09-19T13:43:43+00:00","og_image":[{"width":936,"height":728,"url":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-19-103708.png","type":"image\/png"}],"author":"julian","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"julian","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/#article","isPartOf":{"@id":"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/"},"author":{"name":"julian","@id":"https:\/\/vetanco.com\/es\/#\/schema\/person\/46afb38cfab0fe11bf52a9ded679bfcd"},"headline":"Jorge Winokur, entrevistado por Engormix en IPPE 2017","datePublished":"2017-02-14T13:35:00+00:00","dateModified":"2024-09-19T13:43:43+00:00","mainEntityOfPage":{"@id":"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/"},"wordCount":41,"commentCount":0,"image":{"@id":"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/#primaryimage"},"thumbnailUrl":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-19-103708.png","keywords":["Engormix","Jorge Winokur","Vetanco"],"articleSection":["Eventos","Novedades"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/","url":"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/","name":"Jorge Winokur, entrevistado por Engormix en IPPE 2017 - Vetanco Argentina","isPartOf":{"@id":"https:\/\/vetanco.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/#primaryimage"},"image":{"@id":"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/#primaryimage"},"thumbnailUrl":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-19-103708.png","datePublished":"2017-02-14T13:35:00+00:00","dateModified":"2024-09-19T13:43:43+00:00","author":{"@id":"https:\/\/vetanco.com\/es\/#\/schema\/person\/46afb38cfab0fe11bf52a9ded679bfcd"},"description":"El presidente del laboratorio habl\u00f3 sobre la presencia de la empresa en IPPE 2017 y los desaf\u00edos a los que se enfrenta la industria.","breadcrumb":{"@id":"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/#primaryimage","url":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-19-103708.png","contentUrl":"https:\/\/vetanco.com\/es\/wp-content\/uploads\/2024\/09\/Captura-de-pantalla-2024-09-19-103708.png","width":936,"height":728},{"@type":"BreadcrumbList","@id":"https:\/\/vetanco.com\/es\/jorge-winokur-entrevistado-engormix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/vetanco.com\/es\/"},{"@type":"ListItem","position":2,"name":"Jorge Winokur, entrevistado por Engormix en IPPE 2017"}]},{"@type":"WebSite","@id":"https:\/\/vetanco.com\/es\/#website","url":"https:\/\/vetanco.com\/es\/","name":"Vetanco Argentina","description":"Productos Seguros para Alimentos Seguros","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vetanco.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/vetanco.com\/es\/#\/schema\/person\/46afb38cfab0fe11bf52a9ded679bfcd","name":"julian","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bc79426ed0651bb3545f906602e15ffcf6e4bdb7b02b2394b18705841d207f29?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bc79426ed0651bb3545f906602e15ffcf6e4bdb7b02b2394b18705841d207f29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc79426ed0651bb3545f906602e15ffcf6e4bdb7b02b2394b18705841d207f29?s=96&d=mm&r=g","caption":"julian"},"url":"https:\/\/vetanco.com\/es\/author\/julian\/"}]}},"_links":{"self":[{"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/posts\/9021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/comments?post=9021"}],"version-history":[{"count":1,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/posts\/9021\/revisions"}],"predecessor-version":[{"id":9023,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/posts\/9021\/revisions\/9023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/media\/9022"}],"wp:attachment":[{"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/media?parent=9021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/categories?post=9021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vetanco.com\/es\/wp-json\/wp\/v2\/tags?post=9021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}